{"id":12910,"date":"2025-01-07T16:19:02","date_gmt":"2025-01-07T21:19:02","guid":{"rendered":"https:\/\/museodelcanal.com\/?p=12910"},"modified":"2025-01-07T16:19:02","modified_gmt":"2025-01-07T21:19:02","slug":"%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a","status":"publish","type":"post","link":"https:\/\/museodelcanal.com\/en\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/","title":{"rendered":"\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6 \ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6: \ud835\uddda\ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddee \ud835\udde3\ud835\uddee\ud835\ude01\ud835\uddff\ud835\uddf6\ud835\uddfc\u0301\ud835\ude01\ud835\uddf6\ud835\uddf0\ud835\uddee \ud835\uddf1\ud835\uddf2\ud835\uddf9 \ud835\udff5 \ud835\uddf1\ud835\uddf2 \ud835\uddf2\ud835\uddfb\ud835\uddf2\ud835\uddff\ud835\uddfc"},"content":{"rendered":"<p style=\"text-align: center;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-12911\" src=\"https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1-300x300.jpg 300w, https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1-1024x1024.jpg 1024w, https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1-150x150.jpg 150w, https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1-768x768.jpg 768w, https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1-12x12.jpg 12w, https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1-650x650.jpg 650w, https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1-400x400.jpg 400w, https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1-600x600.jpg 600w, https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1-100x100.jpg 100w, https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1.jpg 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Este 9 de enero, conmemoramos un momento hist\u00f3rico que marc\u00f3 el alma de nuestra naci\u00f3n. En honor a la Gesta del 9 de enero de 1964, te invitamos a recorrer el Museo del Canal, donde podr\u00e1s revivir los eventos que forjaron nuestra identidad y nos unieron como pueblo.<\/p>\n<p>Puertas Abiertas para todos aquellos que deseen explorar, reflexionar y celebrar el legado de valent\u00eda y lucha por nuestra soberan\u00eda. Ven con nosotros a recordar, a conocer y a rendir homenaje a quienes lucharon por nuestros derechos.<\/p>\n<p>Fecha: 9 de enero de 2025<br \/>\nHora: 9:00 AM &#8211; 5:00 PM<br \/>\nUbicaci\u00f3n: Museo del Canal, Ciudad de Panam\u00e1<br \/>\n\ud835\uddd8\ud835\uddfb\ud835\ude01\ud835\uddff\ud835\uddee\ud835\uddf1\ud835\uddee \ud835\uddda\ud835\udde5\ud835\uddd4\ud835\udde7\ud835\udde8\ud835\udddc\ud835\udde7\ud835\uddd4<\/p>","protected":false},"excerpt":{"rendered":"<p>Este 9 de enero, conmemoramos un momento hist\u00f3rico que marc\u00f3 el alma de nuestra naci\u00f3n. En honor a la Gesta del 9 de enero de 1964, te invitamos a recorrer el Museo del Canal, donde podr\u00e1s revivir los eventos que [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":12911,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[98,17],"tags":[],"class_list":["post-12910","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","category-events-programs"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6 \ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6: \ud835\uddda\ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddee \ud835\udde3\ud835\uddee\ud835\ude01\ud835\uddff\ud835\uddf6\ud835\uddfc\u0301\ud835\ude01\ud835\uddf6\ud835\uddf0\ud835\uddee \ud835\uddf1\ud835\uddf2\ud835\uddf9 \ud835\udff5 \ud835\uddf1\ud835\uddf2 \ud835\uddf2\ud835\uddfb\ud835\uddf2\ud835\uddff\ud835\uddfc - Museo del Canal Interoce\u00e1nico de Panam\u00e1<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/museodelcanal.com\/en\/\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6-\ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6-\ud835\uddda\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6 \ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6: \ud835\uddda\ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddee \ud835\udde3\ud835\uddee\ud835\ude01\ud835\uddff\ud835\uddf6\ud835\uddfc\u0301\ud835\ude01\ud835\uddf6\ud835\uddf0\ud835\uddee \ud835\uddf1\ud835\uddf2\ud835\uddf9 \ud835\udff5 \ud835\uddf1\ud835\uddf2 \ud835\uddf2\ud835\uddfb\ud835\uddf2\ud835\uddff\ud835\uddfc - Museo del Canal Interoce\u00e1nico de Panam\u00e1\" \/>\n<meta property=\"og:description\" content=\"Este 9 de enero, conmemoramos un momento hist\u00f3rico que marc\u00f3 el alma de nuestra naci\u00f3n. En honor a la Gesta del 9 de enero de 1964, te invitamos a recorrer el Museo del Canal, donde podr\u00e1s revivir los eventos que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/museodelcanal.com\/en\/\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6-\ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6-\ud835\uddda\/\" \/>\n<meta property=\"og:site_name\" content=\"Museo del Canal Interoce\u00e1nico de Panam\u00e1\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-07T21:19:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Moises Ledezma\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moises Ledezma\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/\"},\"author\":{\"name\":\"Moises Ledezma\",\"@id\":\"https:\/\/museodelcanal.com\/#\/schema\/person\/4fb748689bacc2cc3dd5bbbfef6abbce\"},\"headline\":\"\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6 \ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6: \ud835\uddda\ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddee \ud835\udde3\ud835\uddee\ud835\ude01\ud835\uddff\ud835\uddf6\ud835\uddfc\u0301\ud835\ude01\ud835\uddf6\ud835\uddf0\ud835\uddee \ud835\uddf1\ud835\uddf2\ud835\uddf9 \ud835\udff5 \ud835\uddf1\ud835\uddf2 \ud835\uddf2\ud835\uddfb\ud835\uddf2\ud835\uddff\ud835\uddfc\",\"datePublished\":\"2025-01-07T21:19:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/\"},\"wordCount\":103,\"image\":{\"@id\":\"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1.jpg\",\"articleSection\":[\"Eventos\",\"Events &amp; Programs\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/\",\"url\":\"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/\",\"name\":\"\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6 \ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6: \ud835\uddda\ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddee \ud835\udde3\ud835\uddee\ud835\ude01\ud835\uddff\ud835\uddf6\ud835\uddfc\u0301\ud835\ude01\ud835\uddf6\ud835\uddf0\ud835\uddee \ud835\uddf1\ud835\uddf2\ud835\uddf9 \ud835\udff5 \ud835\uddf1\ud835\uddf2 \ud835\uddf2\ud835\uddfb\ud835\uddf2\ud835\uddff\ud835\uddfc - Museo del Canal Interoce\u00e1nico de Panam\u00e1\",\"isPartOf\":{\"@id\":\"https:\/\/museodelcanal.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1.jpg\",\"datePublished\":\"2025-01-07T21:19:02+00:00\",\"author\":{\"@id\":\"https:\/\/museodelcanal.com\/#\/schema\/person\/4fb748689bacc2cc3dd5bbbfef6abbce\"},\"breadcrumb\":{\"@id\":\"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/#primaryimage\",\"url\":\"https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1.jpg\",\"contentUrl\":\"https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/museodelcanal.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6 \ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6: \ud835\uddda\ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddee \ud835\udde3\ud835\uddee\ud835\ude01\ud835\uddff\ud835\uddf6\ud835\uddfc\u0301\ud835\ude01\ud835\uddf6\ud835\uddf0\ud835\uddee \ud835\uddf1\ud835\uddf2\ud835\uddf9 \ud835\udff5 \ud835\uddf1\ud835\uddf2 \ud835\uddf2\ud835\uddfb\ud835\uddf2\ud835\uddff\ud835\uddfc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/museodelcanal.com\/#website\",\"url\":\"https:\/\/museodelcanal.com\/\",\"name\":\"Museo del Canal Interoce\u00e1nico de Panam\u00e1\",\"description\":\"Explora el pasado para navegar el presente\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/museodelcanal.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/museodelcanal.com\/#\/schema\/person\/4fb748689bacc2cc3dd5bbbfef6abbce\",\"name\":\"Moises Ledezma\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/secure.gravatar.com\/avatar\/cb64bf5af8d1c4227ce087e199fb0d8fc33e8214ff94e0c2a5241104a3a27aeb?s=96&d=mm&r=g\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cb64bf5af8d1c4227ce087e199fb0d8fc33e8214ff94e0c2a5241104a3a27aeb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cb64bf5af8d1c4227ce087e199fb0d8fc33e8214ff94e0c2a5241104a3a27aeb?s=96&d=mm&r=g\",\"caption\":\"Moises Ledezma\"},\"url\":\"https:\/\/museodelcanal.com\/en\/author\/mledezma\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6 \ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6: \ud835\uddda\ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddee \ud835\udde3\ud835\uddee\ud835\ude01\ud835\uddff\ud835\uddf6\ud835\uddfc\u0301\ud835\ude01\ud835\uddf6\ud835\uddf0\ud835\uddee \ud835\uddf1\ud835\uddf2\ud835\uddf9 \ud835\udff5 \ud835\uddf1\ud835\uddf2 \ud835\uddf2\ud835\uddfb\ud835\uddf2\ud835\uddff\ud835\uddfc - Museo del Canal Interoce\u00e1nico de Panam\u00e1","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/museodelcanal.com\/en\/\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6-\ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6-\ud835\uddda\/","og_locale":"en_US","og_type":"article","og_title":"\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6 \ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6: \ud835\uddda\ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddee \ud835\udde3\ud835\uddee\ud835\ude01\ud835\uddff\ud835\uddf6\ud835\uddfc\u0301\ud835\ude01\ud835\uddf6\ud835\uddf0\ud835\uddee \ud835\uddf1\ud835\uddf2\ud835\uddf9 \ud835\udff5 \ud835\uddf1\ud835\uddf2 \ud835\uddf2\ud835\uddfb\ud835\uddf2\ud835\uddff\ud835\uddfc - Museo del Canal Interoce\u00e1nico de Panam\u00e1","og_description":"Este 9 de enero, conmemoramos un momento hist\u00f3rico que marc\u00f3 el alma de nuestra naci\u00f3n. En honor a la Gesta del 9 de enero de 1964, te invitamos a recorrer el Museo del Canal, donde podr\u00e1s revivir los eventos que [&hellip;]","og_url":"https:\/\/museodelcanal.com\/en\/\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6-\ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6-\ud835\uddda\/","og_site_name":"Museo del Canal Interoce\u00e1nico de Panam\u00e1","article_published_time":"2025-01-07T21:19:02+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1.jpg","type":"image\/jpeg"}],"author":"Moises Ledezma","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Moises Ledezma","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/#article","isPartOf":{"@id":"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/"},"author":{"name":"Moises Ledezma","@id":"https:\/\/museodelcanal.com\/#\/schema\/person\/4fb748689bacc2cc3dd5bbbfef6abbce"},"headline":"\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6 \ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6: \ud835\uddda\ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddee \ud835\udde3\ud835\uddee\ud835\ude01\ud835\uddff\ud835\uddf6\ud835\uddfc\u0301\ud835\ude01\ud835\uddf6\ud835\uddf0\ud835\uddee \ud835\uddf1\ud835\uddf2\ud835\uddf9 \ud835\udff5 \ud835\uddf1\ud835\uddf2 \ud835\uddf2\ud835\uddfb\ud835\uddf2\ud835\uddff\ud835\uddfc","datePublished":"2025-01-07T21:19:02+00:00","mainEntityOfPage":{"@id":"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/"},"wordCount":103,"image":{"@id":"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/#primaryimage"},"thumbnailUrl":"https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1.jpg","articleSection":["Eventos","Events &amp; Programs"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/","url":"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/","name":"\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6 \ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6: \ud835\uddda\ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddee \ud835\udde3\ud835\uddee\ud835\ude01\ud835\uddff\ud835\uddf6\ud835\uddfc\u0301\ud835\ude01\ud835\uddf6\ud835\uddf0\ud835\uddee \ud835\uddf1\ud835\uddf2\ud835\uddf9 \ud835\udff5 \ud835\uddf1\ud835\uddf2 \ud835\uddf2\ud835\uddfb\ud835\uddf2\ud835\uddff\ud835\uddfc - Museo del Canal Interoce\u00e1nico de Panam\u00e1","isPartOf":{"@id":"https:\/\/museodelcanal.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/#primaryimage"},"image":{"@id":"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/#primaryimage"},"thumbnailUrl":"https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1.jpg","datePublished":"2025-01-07T21:19:02+00:00","author":{"@id":"https:\/\/museodelcanal.com\/#\/schema\/person\/4fb748689bacc2cc3dd5bbbfef6abbce"},"breadcrumb":{"@id":"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/#primaryimage","url":"https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1.jpg","contentUrl":"https:\/\/museodelcanal.com\/wp-content\/uploads\/2025\/01\/Post-PuertasAbiertas-1.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/museodelcanal.com\/%f0%9d%97%a3%f0%9d%97%a8%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%94%f0%9d%97%95%f0%9d%97%9c%f0%9d%97%98%f0%9d%97%a5%f0%9d%97%a7%f0%9d%97%94%f0%9d%97%a6-%f0%9d%97%9a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/museodelcanal.com\/"},{"@type":"ListItem","position":2,"name":"\ud835\udde3\ud835\udde8\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6 \ud835\uddd4\ud835\uddd5\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde7\ud835\uddd4\ud835\udde6: \ud835\uddda\ud835\uddf2\ud835\ude00\ud835\ude01\ud835\uddee \ud835\udde3\ud835\uddee\ud835\ude01\ud835\uddff\ud835\uddf6\ud835\uddfc\u0301\ud835\ude01\ud835\uddf6\ud835\uddf0\ud835\uddee \ud835\uddf1\ud835\uddf2\ud835\uddf9 \ud835\udff5 \ud835\uddf1\ud835\uddf2 \ud835\uddf2\ud835\uddfb\ud835\uddf2\ud835\uddff\ud835\uddfc"}]},{"@type":"WebSite","@id":"https:\/\/museodelcanal.com\/#website","url":"https:\/\/museodelcanal.com\/","name":"Panama Canal Museum","description":"Explore the past to navigate the present","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/museodelcanal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/museodelcanal.com\/#\/schema\/person\/4fb748689bacc2cc3dd5bbbfef6abbce","name":"Moises Ledezma","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/cb64bf5af8d1c4227ce087e199fb0d8fc33e8214ff94e0c2a5241104a3a27aeb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cb64bf5af8d1c4227ce087e199fb0d8fc33e8214ff94e0c2a5241104a3a27aeb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cb64bf5af8d1c4227ce087e199fb0d8fc33e8214ff94e0c2a5241104a3a27aeb?s=96&d=mm&r=g","caption":"Moises Ledezma"},"url":"https:\/\/museodelcanal.com\/en\/author\/mledezma\/"}]}},"_links":{"self":[{"href":"https:\/\/museodelcanal.com\/en\/wp-json\/wp\/v2\/posts\/12910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/museodelcanal.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/museodelcanal.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/museodelcanal.com\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/museodelcanal.com\/en\/wp-json\/wp\/v2\/comments?post=12910"}],"version-history":[{"count":1,"href":"https:\/\/museodelcanal.com\/en\/wp-json\/wp\/v2\/posts\/12910\/revisions"}],"predecessor-version":[{"id":12912,"href":"https:\/\/museodelcanal.com\/en\/wp-json\/wp\/v2\/posts\/12910\/revisions\/12912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/museodelcanal.com\/en\/wp-json\/wp\/v2\/media\/12911"}],"wp:attachment":[{"href":"https:\/\/museodelcanal.com\/en\/wp-json\/wp\/v2\/media?parent=12910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/museodelcanal.com\/en\/wp-json\/wp\/v2\/categories?post=12910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/museodelcanal.com\/en\/wp-json\/wp\/v2\/tags?post=12910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}